{"id":3420,"date":"2009-07-09T16:29:26","date_gmt":"2009-07-09T19:29:26","guid":{"rendered":"http:\/\/betabligraf.categorymg.com\/?p=3420"},"modified":"2009-07-09T16:29:26","modified_gmt":"2009-07-09T19:29:26","slug":"alimentek-2009","status":"publish","type":"post","link":"https:\/\/bligraf.com\/chile\/2009\/07\/09\/alimentek-2009\/","title":{"rendered":"Alimentek 2009"},"content":{"rendered":"<p>Envase 2009 \u2013 Alimentek 2009: balance de un encuentro exitoso<\/p>\n<div class=\"av-special-heading av-special-heading-h3 avia-builder-el-1 el_before_av_textblock avia-builder-el-first \">\n<div class=\"special-heading-border\">\n<div class=\"avia_textblock \">\n<p><strong>M\u00e1s de 38 mil personas recorrieron la feria y participaron de las actividades acad\u00e9micas.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>La 11\u00ba Exposici\u00f3n Internacional del Envase, Embalaje, ENVASE 2009, y la 6\u00ba Exposici\u00f3n de Maquinarias para el Procesamiento de Alimentos y Bebidas, ALIMENTEK 2009, resultaron impactantes. Las mismas, se llevaron a cabo del 22 al 25 de septiembre en el Centro Costa Salguero, Buenos Aires, Argentina.<\/p>\n<p>Los 38.221 t\u00e9cnicos y profesionales que llegaron de m\u00e1s de 23 paises jerarquizaron la muestra y demostraron la fortaleza del mercado del packaging. Los comentarios m\u00e1s generalizados entre las empresas participantes son de satisfacci\u00f3n por la gran cantidad de contactos establecidos, y por la predisposici\u00f3n a la inversi\u00f3n de los clientes, que en muchos casos se ha traducido en contratos in situ.<\/p>\n<p>Las m\u00e1s recientes innovaciones en l\u00edneas de productos, tecnolog\u00eda de punta en maquinaria de envasado, maquinarias de conversi\u00f3n, tecnolog\u00eda de procesamientos, materiales y contenedores; adem\u00e1s de los \u00faltimos avances en envasado de seguridad, nuevas tecnolog\u00edas gr\u00e1ficas y de impresi\u00f3n, son algunos de los desarrollos que los profesionales y t\u00e9cnicos pudieron observar.<\/p>\n<p>La feria fue un espacio en donde se llevaron a cabo m\u00e1s de 30 actividades acad\u00e9micas y una Ronda de Negocios. La Fundaci\u00f3n Export.Ar, en su rol de agencia de promoci\u00f3n de exportaciones de la Canciller\u00eda Argentina, conjuntamente con el Instituto Argentino del Envase y ProArgentina, presentaron la 1era. Edici\u00f3n de la \u201cRonda de negocios internacional de envases y embalajes, equipos, m\u00e1quinas y materias primas\u201d, con el objetivo principal de incrementar las oportunidades de negocios de exportaci\u00f3n del sector nacional.<\/p>\n<p>Seg\u00fan Keith Pearson, presidente de la WPO \u201cla Exposici\u00f3n Envase Alimentek es sin dudas una de las m\u00e1s importantes del mundo\u201d. Tambi\u00e9n remarc\u00f3, \u201cvendr\u00e1n a\u00f1os muy pr\u00f3spero para la industria del envase y que el sector cumplir\u00e1 un rol fundamental\u201d. Seg\u00fan Pearson, existe un importante crecimiento en la raza humana y la industria del envase y embalaje, posee en este sentido, un rol fundamental para el cuidado y la preservaci\u00f3n de los alimentos as\u00ed como tambi\u00e9n la constante preocupaci\u00f3n por el desarrollo sustentable.<\/p>\n<p>Jorge Acevedo, gerente general del IAE expuso en el transcurso el Acto de Apertura,<\/p>\n<blockquote><p>\u201cArgentina contin\u00faa siendo un mercado muy importante para la industria del envase y embalaje ya que los sectores de alimentos, bebidas, farmac\u00e9utico y cosm\u00e9tica, a pesar de la crisis mundial, siguen desarroll\u00e1ndose.\u00a0Mantener la capacidad de innovar es el desaf\u00edo que enfrenta el sector de envases y embalajes, una actividad con din\u00e1mica propia en este sentido. La natural rotaci\u00f3n de productos, las exigencias est\u00e9ticas y medioambientales y la necesidad de proteger y preservar los productos son los motivos que impulsan constantemente a la actualizaci\u00f3n tecnol\u00f3gica y creativa del segmento.\u201d<\/p><\/blockquote>\n<p>Siguiendo con el Acto Inaugural, la presentaci\u00f3n de Ahmed Omah, secretario general del Instituto de Packaging de Nigeria result\u00f3 sumamente interesante y atractiva para los empresarios presentes. Ofreci\u00f3 un panorama \u00edntegro de la regi\u00f3n nigeriana en donde se pudo evaluar las posibilidades comerciales que ofrece la regi\u00f3n y en donde Argentina resulta sumamente atractiva en cuanto a posibilidades comerciales.<\/p>\n<p>Por \u00faltimo habl\u00f3 el Dr. Enrique Schcolnik, presidente del Instituto Argentino del Envase, en donde remarc\u00f3 con \u00edmpetu la importancia del rol del envase en la vida humana refiri\u00e9ndose a los beneficios que el mismo brinda a la comunidad y en donde ejemplific\u00f3 la labor que viene desarrollando \u00e9l y su familia en la industria desde hace muchos a\u00f1os.<br \/>\nTambi\u00e9n hizo menci\u00f3n al Aniversario del IAE por los 40 a\u00f1os que cumpli\u00f3 en el mes de septiembre con una importante celebraci\u00f3n.<\/p>\n<h4>Datos<\/h4>\n<p>Seg\u00fan los datos registrados, la muestra fue visitada por representantes de los siguientes sectores: un 25% de visitantes del sector industrial, un 22,5% representantes del sector alimenticio, un 10% fueron visitantes del sector de bebidas y un 6.20% pertenecientes al sector qu\u00edmico \/ farmac\u00e9utico. Tambi\u00e9n se hicieron presente representantes de supermercados, servicios, cosm\u00e9tica, limpieza, textil, calzado, agr\u00edcola, de la industria pesquera y de construcci\u00f3n.<\/p>\n<p>El 18% de las personas que visitaron la muestra, seg\u00fan los registros, fueron empresarios, en un 17,6% visitaron la muestra gerentes y directores de los sectores arriba mencionados, y en un 18% p\u00fablico t\u00e9cnico especializado.<\/p>\n<p>De la importante afluencia de visitantes extranjeros que asistieron a Envase \/ Alimentek 2009, estuvieron presentes representantes de los siguientes pa\u00edses: Alemania, Australia, Bolivia, Brasil, Colombia, Corea, Costa Rica, Chile, China, Ecuador, Espa\u00f1a, Estados Unidos, Israel, Italia, Jap\u00f3n, M\u00e9xico, Panam\u00e1, Paraguay, Per\u00fa, Rep\u00fablica Dominicana, Suiza, Uruguay, Venezuela.<\/p>\n<p>En cuanto a la oferta de la Exposici\u00f3n, el 24,10% de los visitantes encuestados manifest\u00f3 que su principal punto de inter\u00e9s eran las maquinarias y los accesorios. El 19,12% declar\u00f3 estar interesado en las materias primas y aditivos, y el 14% en los productos de etiquetados y codificadores. El porcentaje restante manifest\u00f3 principal inter\u00e9s en los sectores de log\u00edstica, servicios, m\u00e1quinas y equipos para embotellado, m\u00e1quinas para el proceso de fabricaci\u00f3n de productos, publicidad y medio ambiente.<\/p>\n<p>&nbsp;<\/p>\n<h4>Mercado<\/h4>\n<p>Seg\u00fan datos proporcionados por el IAE, el mercado del envase y embalaje cerr\u00f3 en 2008 con una facturaci\u00f3n de $10.889 millones, lo que implica un consumo per c\u00e1pita 97 kilos anuales.<\/p>\n<p>El giro del negocio de producci\u00f3n de envases durante 2008 super\u00f3 el mill\u00f3n y medio de toneladas y los segmentos que m\u00e1s se destacaron fueron el del Papel y Cart\u00f3n con el 26%, el Vidrio tambi\u00e9n con el 26% y los envases Pl\u00e1sticos Flexibles con el 23%, seguido de los Pl\u00e1sticos R\u00edgidos. M\u00e1s lejos se encuentran la Madera, con el 20%, y la Hojalata y Metales, con el 5%.<br \/>\nAnalizando la evoluci\u00f3n del sector entre 2003 y 2008, el mayor dinamismo estuvo liderado por el segmento del papel y el cart\u00f3n, con un aumento respecto a 2003 del 40%; seguido por el vidrio, que aument\u00f3 el 34% en el mismo per\u00edodo; y las pl\u00e1sticos, con un 20%.<\/p>\n<p>La pr\u00f3xima edici\u00f3n de Envase \/ Alimentek tendr\u00e1 lugar del 20 al 23 de septiembre de 2011 en el Centro de Exposiciones de Costa Salguero.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Envase 2009 \u2013 Alimentek 2009: balance de un encuentro exitoso M\u00e1s de 38 mil personas recorrieron la feria y participaron de las actividades acad\u00e9micas. La 11\u00ba Exposici\u00f3n Internacional del Envase, Embalaje, ENVASE 2009, y la 6\u00ba Exposici\u00f3n de Maquinarias para el Procesamiento de Alimentos y Bebidas, ALIMENTEK 2009, resultaron impactantes. Las mismas, se llevaron a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2,3],"tags":[22],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/posts\/3420"}],"collection":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/comments?post=3420"}],"version-history":[{"count":0,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/posts\/3420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/media\/3945"}],"wp:attachment":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/media?parent=3420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/categories?post=3420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/tags?post=3420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}