{"id":3475,"date":"2012-02-09T18:12:17","date_gmt":"2012-02-09T21:12:17","guid":{"rendered":"http:\/\/betabligraf.categorymg.com\/?p=3475"},"modified":"2012-02-09T18:12:17","modified_gmt":"2012-02-09T21:12:17","slug":"visual-packaging-en-la-experiencia-de-marca","status":"publish","type":"post","link":"https:\/\/bligraf.com\/chile\/2012\/02\/09\/visual-packaging-en-la-experiencia-de-marca\/","title":{"rendered":"Visual Packaging en la Experiencia de Marca"},"content":{"rendered":"<blockquote><p>\u201cEl envase, al igual que un vendedor creativo, debe usarse para incitar a so\u00f1ar, pero vendiendo la realidad, el packaging es seducci\u00f3n.<\/p>\n<p>Se vende el producto envuelto en un mensaje, envuelto en un sue\u00f1o\u201d.<\/p>\n<p><strong>Presentamos aqu\u00ed como la empresa de Steve Jobs lleva a la realidad estos conceptos.<\/strong><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" title=\"Visual Packaging en la Experiencia de Marca\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/PWFKjZ8U-fU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Construir Experiencias memorables en el cliente ayuda a difundir los valores de la marca. En este proceso, \u00bfqu\u00e9 valor le asignamos al packaging? \u00bfCu\u00e1nto influye el mismo en la imagen mental que la gente tiene de la marca? \u00bfDebemos darle el mismo peso a la apariencia est\u00e9tica del producto que a la publicidad del mismo?<\/p>\n<p>El concepto de \u201cExperiencia de Marca\u201d abarca todos aquellos elementos con los que el cliente se encuentra a la hora de realizar su compra: el producto en s\u00ed mismo, el logo, el packaging, la folleter\u00eda, la publicidad, la forma de exhibici\u00f3n en el punto de venta, los servicios complementarios asociados a la situaci\u00f3n de compra, la mayor o menor facilidad para disponer del producto o servicio, el valor y la utilidad que un determinado consumidor o usuario le da al mismo.<\/p>\n<p>Atender correctamente estos aspectos permite que la persona pueda so\u00f1ar, desear, sentir, decidir, pedir, disfrutar y volver a gozar de una Experiencia de Marca determinada; esto consiste en la creaci\u00f3n de una Experiencia \u00fanica a trav\u00e9s de toda interacci\u00f3n que el cliente tiene con el personal de contacto, productos, servicios y todo aquello que involucre la marca. La misma se traducir\u00e1 luego en los valores, que los clientes esperan y conf\u00edan que la marca pueda brindarle. De los valores generados por esta Experiencia se terminar\u00e1 creando en la mente del cliente una determinada imagen de marca, que es aquello por lo que la misma es conocida en el mercado.<\/p>\n<p>Existen 3 aspectos a tener en cuenta para el dise\u00f1o de una Experiencia de Marca:<\/p>\n<p>La experiencia del producto: incluye, por un lado, los aspectos funcionales del producto (qu\u00e9 tan bien funciona o satisface las necesidades b\u00e1sicas por las cuales fue adquirido) y, por el otro, los aspectos experienciales que \u00e9ste puede brindarle al cliente. Aqu\u00ed entra, por ejemplo, la situaci\u00f3n de uso\/consumo que ese producto genere.<br \/>\nLas comunicaciones experienciales: las comunicaciones publicitarias no solo deben informar y entretener, mostrando las caracter\u00edsticas de un producto o servicio, sino que deben brindarle valor a la integralidad de la oferta que se le ofrece al consumidor\/usuario.<\/p>\n<p>Las comunicaciones (en todas sus variantes, incluyendo las virtuales) pueden ayudar a implementar una adecuada Experiencia de Marca.<\/p>\n<p>El \u201clook and feel\u201d\/la apariencia: es todo aquello que rodea al producto o servicio. El cliente no s\u00f3lo adquiere las caracter\u00edsticas de un producto, sino que adquiere la oferta de una determinada marca, con un logo, packaging y dise\u00f1o particular. El \u201clook and feel\u201d hace referencia a la identidad visual de una marca.<\/p>\n<p>Esta \u00faltima \u00e1rea es fundamental, ya que a trav\u00e9s de laapariencia del producto se revela tanto elposicionamiento de la empresa como el de la marca. Por ello, debe cuidarse la correspondencia entre estos dos factores \u00bfCu\u00e1ntas veces pasamos de largo en la g\u00f3ndola ciertos productos porque, por solo mirar su packaging, creemos que tiene un precio elevado? O, por el contrario, \u00bfnunca nos pas\u00f3 de menospreciar la calidad de un producto por tener un packaging de dise\u00f1o precario y poco innovador?<\/p>\n<p>El look and feel o packaging se convierte en el factor determinante al momento de elegir entre una marca y otra, incluso pesa mucho m\u00e1s que la experiencia que ese producto pueda darme luego, o que todas las publicidades y mensajes comerciales a los que haya estado expuesto. Esto es as\u00ed debido a que en las esferas perceptivas y afectivas del consumidor, elpackaging ES el producto. Act\u00faa como transmisor de los atributos de identidad de la marca, de sus valores y connotaciones. El packaging es el recurso estrat\u00e9gico de la marca que le aporta al consumidor datos irrefutables: calidad del producto, cantidad, colores, personalidad, componentes, atributos relevantes, origen y hasta certificaciones.<\/p>\n<p>En definitiva, es necesario que los dise\u00f1adores de packaging est\u00e9n familiarizados con las cuestiones de branding y con los valores de marca, de modo que el packaging que hayan creado establezca, identifique y refuerce estos valores en el punto de venta y hagan de la marca un recuerdo positivo en la Experiencia del consumidor.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Visual Packaging en la Experiencia de Marca<br \/>\nConstruir Experiencias memorables en el cliente ayuda a difundir los valores de la marca. En este proceso, \u00bfqu\u00e9 valor le asignamos al packaging? \u00bfCu\u00e1nto influye el mismo en la imagen mental que la gente tiene de la marca? \u00bfDebemos darle el mismo peso a la apariencia est\u00e9tica del producto que a la publicidad del mismo?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":[],"categories":[7],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/posts\/3475"}],"collection":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/comments?post=3475"}],"version-history":[{"count":0,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/posts\/3475\/revisions"}],"wp:attachment":[{"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/media?parent=3475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/categories?post=3475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bligraf.com\/chile\/wp-json\/wp\/v2\/tags?post=3475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}